{"id":27584,"date":"2026-05-28T17:14:30","date_gmt":"2026-05-28T15:14:30","guid":{"rendered":"https:\/\/micasaste.com\/?post_type=product&#038;p=27584"},"modified":"2026-06-29T11:12:50","modified_gmt":"2026-06-29T09:12:50","slug":"robe-leela-rose-leopard","status":"publish","type":"product","link":"https:\/\/micasaste.com\/en\/shop\/robe-leela-rose-leopard\/","title":{"rendered":"Robe Leela Rose L\u00e9opard"},"content":{"rendered":"<p data-start=\"404\" data-end=\"695\">La robe Leela Bleu Rose L\u00e9opard refl\u00e8te l\u2019\u00e9l\u00e9gance naturelle et le style boh\u00e8me de Micasast\u00e9. Confectionn\u00e9e en 100 % coton, elle procure une sensation de douceur et de l\u00e9g\u00e8ret\u00e9 d\u00e8s que vous l\u2019enfilez. Son tissu respirant la rend id\u00e9ale pour les journ\u00e9es ensoleill\u00e9es comme pour les soir\u00e9es plus douces.<\/p>\n<p data-start=\"697\" data-end=\"973\">Son d\u00e9collet\u00e9 en V met subtilement en valeur le buste. Ensuite, sa coupe fluide accompagne les mouvements avec gr\u00e2ce. La ceinture \u00e0 nouer souligne la taille et permet d\u2019ajuster la silhouette selon vos envies. Ainsi, vous cr\u00e9ez facilement un look structur\u00e9 ou plus d\u00e9contract\u00e9.<\/p>\n<p data-start=\"975\" data-end=\"1207\">Les manches mi-longues apportent une touche d\u2019\u00e9l\u00e9gance suppl\u00e9mentaire. De plus, les d\u00e9tails contrast\u00e9s aux poignets ajoutent du caract\u00e8re \u00e0 la robe. Chaque finition r\u00e9v\u00e8le le soin apport\u00e9 \u00e0 la cr\u00e9ation et renforce son allure unique.<\/p>\n<p data-start=\"1209\" data-end=\"1512\">Disponible en 12 imprim\u00e9s diff\u00e9rents, la robe Leela offre une grande libert\u00e9 de style. Optez pour des motifs vibrants pour un look affirm\u00e9. \u00c0 l\u2019inverse, choisissez des imprim\u00e9s plus doux pour une silhouette subtile et raffin\u00e9e. Chaque mod\u00e8le poss\u00e8de son identit\u00e9, ce qui rend chaque robe presque unique.<\/p>\n<p data-start=\"1514\" data-end=\"1716\">Portez-la avec des sandales plates en journ\u00e9e pour un style casual. Puis, associez-la \u00e0 des accessoires plus habill\u00e9s pour une allure \u00e9l\u00e9gante en soir\u00e9e. Elle s\u2019adapte facilement \u00e0 toutes les occasions.<\/p>\n<p data-start=\"1718\" data-end=\"1964\">Enfin, comme toutes les cr\u00e9ations Micasast\u00e9, la robe Leela est fabriqu\u00e9e en Inde selon un savoir-faire artisanal. Elle incarne une mode authentique, responsable et pleine de charme. Une pi\u00e8ce incontournable pour un dressing f\u00e9minin et intemporel.<\/p>","protected":false},"excerpt":{"rendered":"<p>Robe longue Leela<\/p>\n<p>100 % coton, fluide et l\u00e9g\u00e8re.<\/p>\n<p><strong>Taille Unique<\/strong> et ajustable gr\u00e2ce \u00e0 sa ceinture.<\/p>\n<p>Disponible en 12 imprim\u00e9s uniques pour un style boh\u00e8me chic.<\/p>","protected":false},"featured_media":27585,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[397,291],"product_tag":[398],"class_list":["post-27584","product","type-product","status-publish","has-post-thumbnail","product_cat-robe-imprimee","product_cat-vetements-vetements-3","product_tag-robe","first","outofstock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Robe Leela Rose L\u00e9opard - Longue et tendance | Micasast\u00e9<\/title>\n<meta name=\"description\" content=\"Craquez pour la robe Leela Rose L\u00e9opard. Elle existe en 12 imprim\u00e9s uniques, coupe fluide et ceinture ajustable pour un look boh\u00e8me chic et \u00e9l\u00e9gant.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/micasaste.com\/en\/shop\/robe-leela-rose-leopard\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Robe Leela Rose L\u00e9opard - Longue et tendance | Micasast\u00e9\" \/>\n<meta property=\"og:description\" content=\"Craquez pour la robe Leela Rose L\u00e9opard. Elle existe en 12 imprim\u00e9s uniques, coupe fluide et ceinture ajustable pour un look boh\u00e8me chic et \u00e9l\u00e9gant.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/micasaste.com\/en\/shop\/robe-leela-rose-leopard\/\" \/>\n<meta property=\"og:site_name\" content=\"Micasast\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Micasast-100208301386552\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T09:12:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/micasaste.com\/wp-content\/uploads\/2020\/05\/micasaste-facebook-share.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/micasaste.com\\\/shop\\\/robe-leela-rose-leopard\\\/\",\"url\":\"https:\\\/\\\/micasaste.com\\\/shop\\\/robe-leela-rose-leopard\\\/\",\"name\":\"La Robe Leela Rose L\u00e9opard - Longue et tendance | Micasast\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/micasaste.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/micasaste.com\\\/shop\\\/robe-leela-rose-leopard\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/micasaste.com\\\/shop\\\/robe-leela-rose-leopard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/micasaste.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/1-Robe-Leela-Rose-Leopard-.jpeg\",\"datePublished\":\"2026-05-28T15:14:30+00:00\",\"dateModified\":\"2026-06-29T09:12:50+00:00\",\"description\":\"Craquez pour la robe Leela Rose L\u00e9opard. Elle existe en 12 imprim\u00e9s uniques, coupe fluide et ceinture ajustable pour un look boh\u00e8me chic et \u00e9l\u00e9gant.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/micasaste.com\\\/shop\\\/robe-leela-rose-leopard\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/micasaste.com\\\/shop\\\/robe-leela-rose-leopard\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/micasaste.com\\\/shop\\\/robe-leela-rose-leopard\\\/#primaryimage\",\"url\":\"https:\\\/\\\/micasaste.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/1-Robe-Leela-Rose-Leopard-.jpeg\",\"contentUrl\":\"https:\\\/\\\/micasaste.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/1-Robe-Leela-Rose-Leopard-.jpeg\",\"width\":1800,\"height\":2400,\"caption\":\"Robe Leela Rose L\u00e9opard, une robe longue col V, elle se ceinture \u00e0 la taille. Manche 3\\\/4\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/micasaste.com\\\/shop\\\/robe-leela-rose-leopard\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/micasaste.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collection\",\"item\":\"https:\\\/\\\/micasaste.com\\\/shop-collection-femme\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"V\u00eatements\",\"item\":\"https:\\\/\\\/micasaste.com\\\/categorie\\\/vetements-vetements-3\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Robe imprim\u00e9e\",\"item\":\"https:\\\/\\\/micasaste.com\\\/categorie\\\/vetements-vetements-3\\\/robe-imprimee\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Robe Leela Rose L\u00e9opard\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/micasaste.com\\\/#website\",\"url\":\"https:\\\/\\\/micasaste.com\\\/\",\"name\":\"Micasast\u00e9\",\"description\":\"V\u00eatements et Accessoires pour Femme \",\"publisher\":{\"@id\":\"https:\\\/\\\/micasaste.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/micasaste.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/micasaste.com\\\/#organization\",\"name\":\"MicasaSt\u00e9\",\"url\":\"https:\\\/\\\/micasaste.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/micasaste.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/micasaste.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-micasaste.svg\",\"contentUrl\":\"https:\\\/\\\/micasaste.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-micasaste.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"MicasaSt\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/micasaste.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Micasast-100208301386552\\\/\",\"https:\\\/\\\/www.instagram.com\\\/micasaste\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Robe Leela Rose L\u00e9opard - Longue et tendance | Micasast\u00e9","description":"Craquez pour la robe Leela Rose L\u00e9opard. Elle existe en 12 imprim\u00e9s uniques, coupe fluide et ceinture ajustable pour un look boh\u00e8me chic et \u00e9l\u00e9gant.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/micasaste.com\/en\/shop\/robe-leela-rose-leopard\/","og_locale":"en_US","og_type":"article","og_title":"La Robe Leela Rose L\u00e9opard - Longue et tendance | Micasast\u00e9","og_description":"Craquez pour la robe Leela Rose L\u00e9opard. Elle existe en 12 imprim\u00e9s uniques, coupe fluide et ceinture ajustable pour un look boh\u00e8me chic et \u00e9l\u00e9gant.","og_url":"https:\/\/micasaste.com\/en\/shop\/robe-leela-rose-leopard\/","og_site_name":"Micasast\u00e9","article_publisher":"https:\/\/www.facebook.com\/Micasast-100208301386552\/","article_modified_time":"2026-06-29T09:12:50+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/micasaste.com\/wp-content\/uploads\/2020\/05\/micasaste-facebook-share.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/micasaste.com\/shop\/robe-leela-rose-leopard\/","url":"https:\/\/micasaste.com\/shop\/robe-leela-rose-leopard\/","name":"La Robe Leela Rose L\u00e9opard - Longue et tendance | Micasast\u00e9","isPartOf":{"@id":"https:\/\/micasaste.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/micasaste.com\/shop\/robe-leela-rose-leopard\/#primaryimage"},"image":{"@id":"https:\/\/micasaste.com\/shop\/robe-leela-rose-leopard\/#primaryimage"},"thumbnailUrl":"https:\/\/micasaste.com\/wp-content\/uploads\/2026\/05\/1-Robe-Leela-Rose-Leopard-.jpeg","datePublished":"2026-05-28T15:14:30+00:00","dateModified":"2026-06-29T09:12:50+00:00","description":"Craquez pour la robe Leela Rose L\u00e9opard. Elle existe en 12 imprim\u00e9s uniques, coupe fluide et ceinture ajustable pour un look boh\u00e8me chic et \u00e9l\u00e9gant.","breadcrumb":{"@id":"https:\/\/micasaste.com\/shop\/robe-leela-rose-leopard\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/micasaste.com\/shop\/robe-leela-rose-leopard\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/micasaste.com\/shop\/robe-leela-rose-leopard\/#primaryimage","url":"https:\/\/micasaste.com\/wp-content\/uploads\/2026\/05\/1-Robe-Leela-Rose-Leopard-.jpeg","contentUrl":"https:\/\/micasaste.com\/wp-content\/uploads\/2026\/05\/1-Robe-Leela-Rose-Leopard-.jpeg","width":1800,"height":2400,"caption":"Robe Leela Rose L\u00e9opard, une robe longue col V, elle se ceinture \u00e0 la taille. Manche 3\/4"},{"@type":"BreadcrumbList","@id":"https:\/\/micasaste.com\/shop\/robe-leela-rose-leopard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/micasaste.com\/"},{"@type":"ListItem","position":2,"name":"Collection","item":"https:\/\/micasaste.com\/shop-collection-femme\/"},{"@type":"ListItem","position":3,"name":"V\u00eatements","item":"https:\/\/micasaste.com\/categorie\/vetements-vetements-3\/"},{"@type":"ListItem","position":4,"name":"Robe imprim\u00e9e","item":"https:\/\/micasaste.com\/categorie\/vetements-vetements-3\/robe-imprimee\/"},{"@type":"ListItem","position":5,"name":"Robe Leela Rose L\u00e9opard"}]},{"@type":"WebSite","@id":"https:\/\/micasaste.com\/#website","url":"https:\/\/micasaste.com\/","name":"Micasast\u00e9","description":"V\u00eatements et Accessoires pour Femme","publisher":{"@id":"https:\/\/micasaste.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/micasaste.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/micasaste.com\/#organization","name":"MicasaSt\u00e9","url":"https:\/\/micasaste.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/micasaste.com\/#\/schema\/logo\/image\/","url":"https:\/\/micasaste.com\/wp-content\/uploads\/2020\/04\/logo-micasaste.svg","contentUrl":"https:\/\/micasaste.com\/wp-content\/uploads\/2020\/04\/logo-micasaste.svg","width":"1024","height":"1024","caption":"MicasaSt\u00e9"},"image":{"@id":"https:\/\/micasaste.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Micasast-100208301386552\/","https:\/\/www.instagram.com\/micasaste\/"]}]}},"_links":{"self":[{"href":"https:\/\/micasaste.com\/en\/wp-json\/wp\/v2\/product\/27584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/micasaste.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/micasaste.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/micasaste.com\/en\/wp-json\/wp\/v2\/comments?post=27584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/micasaste.com\/en\/wp-json\/wp\/v2\/media\/27585"}],"wp:attachment":[{"href":"https:\/\/micasaste.com\/en\/wp-json\/wp\/v2\/media?parent=27584"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/micasaste.com\/en\/wp-json\/wp\/v2\/product_brand?post=27584"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/micasaste.com\/en\/wp-json\/wp\/v2\/product_cat?post=27584"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/micasaste.com\/en\/wp-json\/wp\/v2\/product_tag?post=27584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}